{"id":102,"date":"2026-08-15T11:29:13","date_gmt":"2026-08-15T11:29:13","guid":{"rendered":"https:\/\/stainless-steel-cookware.com\/?page_id=102"},"modified":"2026-08-15T11:29:33","modified_gmt":"2026-08-15T11:29:33","slug":"casseroles-stockpots","status":"publish","type":"page","link":"https:\/\/stainless-steel-cookware.com\/ja\/casseroles-stockpots\/","title":{"rendered":"Casseroles &amp; Stockpots"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":14,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-102","page","type-page","status-publish","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"_links":{"self":[{"href":"https:\/\/stainless-steel-cookware.com\/ja\/wp-json\/wp\/v2\/pages\/102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stainless-steel-cookware.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stainless-steel-cookware.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stainless-steel-cookware.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stainless-steel-cookware.com\/ja\/wp-json\/wp\/v2\/comments?post=102"}],"version-history":[{"count":1,"href":"https:\/\/stainless-steel-cookware.com\/ja\/wp-json\/wp\/v2\/pages\/102\/revisions"}],"predecessor-version":[{"id":103,"href":"https:\/\/stainless-steel-cookware.com\/ja\/wp-json\/wp\/v2\/pages\/102\/revisions\/103"}],"wp:attachment":[{"href":"https:\/\/stainless-steel-cookware.com\/ja\/wp-json\/wp\/v2\/media?parent=102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}